{"id":6616,"date":"2022-08-11T18:09:49","date_gmt":"2022-08-11T18:09:49","guid":{"rendered":"https:\/\/globaltaxjustice.org\/?post_type=event&#038;p=6616"},"modified":"2022-08-11T18:09:49","modified_gmt":"2022-08-11T18:09:49","slug":"los-retos-de-la-proxima-reforma-tributaria-una-mirada-al-contexto-internacional","status":"publish","type":"event","link":"https:\/\/globaltaxjustice.org\/es\/eventos\/los-retos-de-la-proxima-reforma-tributaria-una-mirada-al-contexto-internacional\/","title":{"rendered":"Los Retos de la Pr\u00f3xima Reforma Tributaria: Una mirada al contexto internacional"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">Programa completo\u00a0<\/span><a href=\"http:\/\/www.fes-colombia.org\/fileadmin\/user_upload\/Programa_def.pdf\"><span style=\"font-weight: 400;\">aqu\u00ed<\/span><\/a><\/p>\n<p><span style=\"font-weight: 400;\">Con Jos\u00e9 Antonio Ocampo, Codirector del Banco de la Rep\u00fablica de Colombia y Presidente de la Comisi\u00f3n Independiente para la Reforma de la Fiscalidad Internacional.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">El panelista internacional Dr. Francisco Saffie de la Universidad Adolfo Iba\u00f1ez presentar\u00e1 \u00ab\u00bfC\u00f3mo luchar contra el fraude fiscal ?\u00bb\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">INSCR\u00cdBETE AQU\u00cd:\u00a0<\/span><a href=\"https:\/\/t.co\/24RAkHpyW4\"><span style=\"font-weight: 400;\">https:\/\/bit.ly\/2EDSGCB<\/span><\/a><\/p>\n\n","protected":false},"excerpt":{"rendered":"<p>Programa completo aqu\u00ed Con Jos\u00e9 Antonio Ocampo, Codirector del Banco de la Rep\u00fablica de Colombia y Presidente de la Comi<\/p>\n","protected":false},"featured_media":6617,"template":"","thematic-area":[135],"year":[20],"class_list":["post-6616","event","type-event","status-publish","has-post-thumbnail","hentry","thematic-area-un-tax-convention","year-20"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Los Retos de la Pr\u00f3xima Reforma Tributaria: Una mirada al contexto internacional - Global Tax Justice<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/globaltaxjustice.org\/es\/eventos\/los-retos-de-la-proxima-reforma-tributaria-una-mirada-al-contexto-internacional\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Los Retos de la Pr\u00f3xima Reforma Tributaria: Una mirada al contexto internacional - Global Tax Justice\" \/>\n<meta property=\"og:description\" content=\"Programa completo aqu\u00ed Con Jos\u00e9 Antonio Ocampo, Codirector del Banco de la Rep\u00fablica de Colombia y Presidente de la Comi\" \/>\n<meta property=\"og:url\" content=\"https:\/\/globaltaxjustice.org\/es\/eventos\/los-retos-de-la-proxima-reforma-tributaria-una-mirada-al-contexto-internacional\/\" \/>\n<meta property=\"og:site_name\" content=\"Global Tax Justice\" \/>\n<meta property=\"og:image\" content=\"https:\/\/globaltaxjustice.org\/wp-content\/uploads\/2022\/08\/2018-05-03-Los-Retos-de-la-Proxima-Reforma-Tributaria-Una-mirada-al-contexto-internacional-ES-IMAGEM-2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1462\" \/>\n\t<meta property=\"og:image:height\" content=\"234\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/globaltaxjustice.org\\\/es\\\/eventos\\\/los-retos-de-la-proxima-reforma-tributaria-una-mirada-al-contexto-internacional\\\/\",\"url\":\"https:\\\/\\\/globaltaxjustice.org\\\/es\\\/eventos\\\/los-retos-de-la-proxima-reforma-tributaria-una-mirada-al-contexto-internacional\\\/\",\"name\":\"Los Retos de la Pr\u00f3xima Reforma Tributaria: Una mirada al contexto internacional - Global Tax Justice\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/globaltaxjustice.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/globaltaxjustice.org\\\/es\\\/eventos\\\/los-retos-de-la-proxima-reforma-tributaria-una-mirada-al-contexto-internacional\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/globaltaxjustice.org\\\/es\\\/eventos\\\/los-retos-de-la-proxima-reforma-tributaria-una-mirada-al-contexto-internacional\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/globaltaxjustice.org\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/2018-05-03-Los-Retos-de-la-Proxima-Reforma-Tributaria-Una-mirada-al-contexto-internacional-ES-IMAGEM-2.png\",\"datePublished\":\"2022-08-11T18:09:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/globaltaxjustice.org\\\/es\\\/eventos\\\/los-retos-de-la-proxima-reforma-tributaria-una-mirada-al-contexto-internacional\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/globaltaxjustice.org\\\/es\\\/eventos\\\/los-retos-de-la-proxima-reforma-tributaria-una-mirada-al-contexto-internacional\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/globaltaxjustice.org\\\/es\\\/eventos\\\/los-retos-de-la-proxima-reforma-tributaria-una-mirada-al-contexto-internacional\\\/#primaryimage\",\"url\":\"https:\\\/\\\/globaltaxjustice.org\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/2018-05-03-Los-Retos-de-la-Proxima-Reforma-Tributaria-Una-mirada-al-contexto-internacional-ES-IMAGEM-2.png\",\"contentUrl\":\"https:\\\/\\\/globaltaxjustice.org\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/2018-05-03-Los-Retos-de-la-Proxima-Reforma-Tributaria-Una-mirada-al-contexto-internacional-ES-IMAGEM-2.png\",\"width\":1462,\"height\":234},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/globaltaxjustice.org\\\/es\\\/eventos\\\/los-retos-de-la-proxima-reforma-tributaria-una-mirada-al-contexto-internacional\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/globaltaxjustice.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Events\",\"item\":\"https:\\\/\\\/globaltaxjustice.org\\\/es\\\/eventos\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Los Retos de la Pr\u00f3xima Reforma Tributaria: Una mirada al contexto internacional\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/globaltaxjustice.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/globaltaxjustice.org\\\/es\\\/\",\"name\":\"Global Tax Justice\",\"description\":\"Just another WordPress site\",\"publisher\":{\"@id\":\"https:\\\/\\\/globaltaxjustice.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/globaltaxjustice.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/globaltaxjustice.org\\\/es\\\/#organization\",\"name\":\"Global Tax Justice\",\"url\":\"https:\\\/\\\/globaltaxjustice.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/globaltaxjustice.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/globaltaxjustice.org\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo_header.svg\",\"contentUrl\":\"https:\\\/\\\/globaltaxjustice.org\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo_header.svg\",\"width\":229,\"height\":40,\"caption\":\"Global Tax Justice\"},\"image\":{\"@id\":\"https:\\\/\\\/globaltaxjustice.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Los Retos de la Pr\u00f3xima Reforma Tributaria: Una mirada al contexto internacional - Global Tax Justice","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/globaltaxjustice.org\/es\/eventos\/los-retos-de-la-proxima-reforma-tributaria-una-mirada-al-contexto-internacional\/","og_locale":"es_ES","og_type":"article","og_title":"Los Retos de la Pr\u00f3xima Reforma Tributaria: Una mirada al contexto internacional - Global Tax Justice","og_description":"Programa completo aqu\u00ed Con Jos\u00e9 Antonio Ocampo, Codirector del Banco de la Rep\u00fablica de Colombia y Presidente de la Comi","og_url":"https:\/\/globaltaxjustice.org\/es\/eventos\/los-retos-de-la-proxima-reforma-tributaria-una-mirada-al-contexto-internacional\/","og_site_name":"Global Tax Justice","og_image":[{"width":1462,"height":234,"url":"https:\/\/globaltaxjustice.org\/wp-content\/uploads\/2022\/08\/2018-05-03-Los-Retos-de-la-Proxima-Reforma-Tributaria-Una-mirada-al-contexto-internacional-ES-IMAGEM-2.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/globaltaxjustice.org\/es\/eventos\/los-retos-de-la-proxima-reforma-tributaria-una-mirada-al-contexto-internacional\/","url":"https:\/\/globaltaxjustice.org\/es\/eventos\/los-retos-de-la-proxima-reforma-tributaria-una-mirada-al-contexto-internacional\/","name":"Los Retos de la Pr\u00f3xima Reforma Tributaria: Una mirada al contexto internacional - Global Tax Justice","isPartOf":{"@id":"https:\/\/globaltaxjustice.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/globaltaxjustice.org\/es\/eventos\/los-retos-de-la-proxima-reforma-tributaria-una-mirada-al-contexto-internacional\/#primaryimage"},"image":{"@id":"https:\/\/globaltaxjustice.org\/es\/eventos\/los-retos-de-la-proxima-reforma-tributaria-una-mirada-al-contexto-internacional\/#primaryimage"},"thumbnailUrl":"https:\/\/globaltaxjustice.org\/wp-content\/uploads\/2022\/08\/2018-05-03-Los-Retos-de-la-Proxima-Reforma-Tributaria-Una-mirada-al-contexto-internacional-ES-IMAGEM-2.png","datePublished":"2022-08-11T18:09:49+00:00","breadcrumb":{"@id":"https:\/\/globaltaxjustice.org\/es\/eventos\/los-retos-de-la-proxima-reforma-tributaria-una-mirada-al-contexto-internacional\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/globaltaxjustice.org\/es\/eventos\/los-retos-de-la-proxima-reforma-tributaria-una-mirada-al-contexto-internacional\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/globaltaxjustice.org\/es\/eventos\/los-retos-de-la-proxima-reforma-tributaria-una-mirada-al-contexto-internacional\/#primaryimage","url":"https:\/\/globaltaxjustice.org\/wp-content\/uploads\/2022\/08\/2018-05-03-Los-Retos-de-la-Proxima-Reforma-Tributaria-Una-mirada-al-contexto-internacional-ES-IMAGEM-2.png","contentUrl":"https:\/\/globaltaxjustice.org\/wp-content\/uploads\/2022\/08\/2018-05-03-Los-Retos-de-la-Proxima-Reforma-Tributaria-Una-mirada-al-contexto-internacional-ES-IMAGEM-2.png","width":1462,"height":234},{"@type":"BreadcrumbList","@id":"https:\/\/globaltaxjustice.org\/es\/eventos\/los-retos-de-la-proxima-reforma-tributaria-una-mirada-al-contexto-internacional\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/globaltaxjustice.org\/es\/"},{"@type":"ListItem","position":2,"name":"Events","item":"https:\/\/globaltaxjustice.org\/es\/eventos\/"},{"@type":"ListItem","position":3,"name":"Los Retos de la Pr\u00f3xima Reforma Tributaria: Una mirada al contexto internacional"}]},{"@type":"WebSite","@id":"https:\/\/globaltaxjustice.org\/es\/#website","url":"https:\/\/globaltaxjustice.org\/es\/","name":"Global Tax Justice","description":"Just another WordPress site","publisher":{"@id":"https:\/\/globaltaxjustice.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/globaltaxjustice.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/globaltaxjustice.org\/es\/#organization","name":"Global Tax Justice","url":"https:\/\/globaltaxjustice.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/globaltaxjustice.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/globaltaxjustice.org\/wp-content\/uploads\/2024\/10\/logo_header.svg","contentUrl":"https:\/\/globaltaxjustice.org\/wp-content\/uploads\/2024\/10\/logo_header.svg","width":229,"height":40,"caption":"Global Tax Justice"},"image":{"@id":"https:\/\/globaltaxjustice.org\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/globaltaxjustice.org\/es\/wp-json\/wp\/v2\/event\/6616","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/globaltaxjustice.org\/es\/wp-json\/wp\/v2\/event"}],"about":[{"href":"https:\/\/globaltaxjustice.org\/es\/wp-json\/wp\/v2\/types\/event"}],"version-history":[{"count":0,"href":"https:\/\/globaltaxjustice.org\/es\/wp-json\/wp\/v2\/event\/6616\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/globaltaxjustice.org\/es\/wp-json\/wp\/v2\/media\/6617"}],"wp:attachment":[{"href":"https:\/\/globaltaxjustice.org\/es\/wp-json\/wp\/v2\/media?parent=6616"}],"wp:term":[{"taxonomy":"thematic-area","embeddable":true,"href":"https:\/\/globaltaxjustice.org\/es\/wp-json\/wp\/v2\/thematic-area?post=6616"},{"taxonomy":"year","embeddable":true,"href":"https:\/\/globaltaxjustice.org\/es\/wp-json\/wp\/v2\/year?post=6616"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}