{"id":6787,"date":"2022-08-11T20:35:06","date_gmt":"2022-08-11T20:35:06","guid":{"rendered":"https:\/\/globaltaxjustice.org\/?post_type=news&#038;p=6787"},"modified":"2022-08-11T20:35:06","modified_gmt":"2022-08-11T20:35:06","slug":"el-escandalo-de-la-desigualdad-2","status":"publish","type":"news","link":"https:\/\/globaltaxjustice.org\/es\/noticias\/el-escandalo-de-la-desigualdad-2\/","title":{"rendered":"El esc\u00e1ndalo de la desigualdad 2"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">Christian Aid acaba de publicar\u00a0la versi\u00f3n actualizada de su\u00a0estudio de 2012<\/span><i><span style=\"font-weight: 400;\">, \u201cEl esc\u00e1ndalo de la desigualdad 2\u201d<\/span><\/i><span style=\"font-weight: 400;\">, en el que detalla las m\u00faltiples desigualdades que existen en Am\u00e9rica Latina.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Como se\u00f1ala el resumen ejecutivo del informe, este se centra sobre la b\u00fasqueda de claves para reducir la desigualdad. \u201cEste informe se centra en \u00e1reas claves en las que Christian Aid\/InspirAction y sus contrapartes de toda Am\u00e9rica Latina y el Caribe reclaman y proponen acciones para reducir las desigualdades. No abordamos cada desigualdad, pero resaltamos algunas de las formas principales de desigualdad que consideramos que afectan al desarrollo de la regi\u00f3n, como lo demuestra el trabajo con nuestras contrapartes. Las mujeres se ven desproporcionadamente afectadas por la pobreza, marginaci\u00f3n, discriminaci\u00f3n, violencia, cambio clim\u00e1tico y ausencia de oportunidades pol\u00edticas o de empleo.\u00a0Para que se d\u00e9 un cambio, los gobiernos tienen que desarrollar y poner en vigor medidas pol\u00edticas efectivas que aborden las distintas facetas de la desigualdad.\u201d<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Las m\u00faltiples caras de la desigualdad en Am\u00e9rica Latina y el Caribe<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En su visi\u00f3n general de la desigualdad en Am\u00e9rica Latina y el Caribe, la ONG aborda la justicia fiscal entre 6 temas, de los cuales identidad racial y \u00e9tnica, gobernabilidad y poder, violencia, trabajo digno y desarrollo bajo en carbono.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Puede leer el reporte\u00a0<\/span><a href=\"http:\/\/globaltaxjustice.org\/wp-content\/uploads\/2022\/08\/2017-03-31-aqui-en-espanol-ES-PDF.pdf\"><span style=\"font-weight: 400;\">aqu\u00ed en espa\u00f1ol<\/span><\/a><span style=\"font-weight: 400;\">\u00a0y\u00a0<\/span><a href=\"http:\/\/globaltaxjustice.org\/wp-content\/uploads\/2022\/08\/2017-03-31aqui-en-inlges.-EN-PDF-1.pdf\"><span style=\"font-weight: 400;\">aqu\u00ed en inlg\u00e9s<\/span><\/a><span style=\"font-weight: 400;\">.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Christian Aid acaba de publicar la versi\u00f3n actualizada de su estudio de 2012, \u201cEl esc\u00e1ndalo de la desigualdad 2\u201d, en el <\/p>\n","protected":false},"featured_media":6788,"template":"","thematic-area":[122],"year":[115],"resource-type":[],"class_list":["post-6787","news","type-news","status-publish","has-post-thumbnail","hentry","thematic-area-fiscalidad-y-extractivas","year-2017-es"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El esc\u00e1ndalo de la desigualdad 2 - Global Tax Justice<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/globaltaxjustice.org\/es\/noticias\/el-escandalo-de-la-desigualdad-2\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El esc\u00e1ndalo de la desigualdad 2 - Global Tax Justice\" \/>\n<meta property=\"og:description\" content=\"Christian Aid acaba de publicar la versi\u00f3n actualizada de su estudio de 2012, \u201cEl esc\u00e1ndalo de la desigualdad 2\u201d, en el\" \/>\n<meta property=\"og:url\" content=\"https:\/\/globaltaxjustice.org\/es\/noticias\/el-escandalo-de-la-desigualdad-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Global Tax Justice\" \/>\n<meta property=\"og:image\" content=\"https:\/\/globaltaxjustice.org\/wp-content\/uploads\/2022\/08\/2017-03-31-El-escandalo-de-la-desigualdad-2-ES-IMAGEM-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"742\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/globaltaxjustice.org\/es\/noticias\/el-escandalo-de-la-desigualdad-2\/\",\"url\":\"https:\/\/globaltaxjustice.org\/es\/noticias\/el-escandalo-de-la-desigualdad-2\/\",\"name\":\"El esc\u00e1ndalo de la desigualdad 2 - Global Tax Justice\",\"isPartOf\":{\"@id\":\"https:\/\/globaltaxjustice.org\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/globaltaxjustice.org\/es\/noticias\/el-escandalo-de-la-desigualdad-2\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/globaltaxjustice.org\/es\/noticias\/el-escandalo-de-la-desigualdad-2\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/globaltaxjustice.org\/wp-content\/uploads\/2022\/08\/2017-03-31-El-escandalo-de-la-desigualdad-2-ES-IMAGEM-2.jpg\",\"datePublished\":\"2022-08-11T20:35:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/globaltaxjustice.org\/es\/noticias\/el-escandalo-de-la-desigualdad-2\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/globaltaxjustice.org\/es\/noticias\/el-escandalo-de-la-desigualdad-2\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/globaltaxjustice.org\/es\/noticias\/el-escandalo-de-la-desigualdad-2\/#primaryimage\",\"url\":\"https:\/\/globaltaxjustice.org\/wp-content\/uploads\/2022\/08\/2017-03-31-El-escandalo-de-la-desigualdad-2-ES-IMAGEM-2.jpg\",\"contentUrl\":\"https:\/\/globaltaxjustice.org\/wp-content\/uploads\/2022\/08\/2017-03-31-El-escandalo-de-la-desigualdad-2-ES-IMAGEM-2.jpg\",\"width\":1024,\"height\":742},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/globaltaxjustice.org\/es\/noticias\/el-escandalo-de-la-desigualdad-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/globaltaxjustice.org\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News\",\"item\":\"https:\/\/globaltaxjustice.org\/es\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"El esc\u00e1ndalo de la desigualdad 2\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/globaltaxjustice.org\/es\/#website\",\"url\":\"https:\/\/globaltaxjustice.org\/es\/\",\"name\":\"Global Tax Justice\",\"description\":\"Just another WordPress site\",\"publisher\":{\"@id\":\"https:\/\/globaltaxjustice.org\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/globaltaxjustice.org\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/globaltaxjustice.org\/es\/#organization\",\"name\":\"Global Tax Justice\",\"url\":\"https:\/\/globaltaxjustice.org\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/globaltaxjustice.org\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/globaltaxjustice.org\/wp-content\/uploads\/2024\/10\/logo_header.svg\",\"contentUrl\":\"https:\/\/globaltaxjustice.org\/wp-content\/uploads\/2024\/10\/logo_header.svg\",\"width\":229,\"height\":40,\"caption\":\"Global Tax Justice\"},\"image\":{\"@id\":\"https:\/\/globaltaxjustice.org\/es\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El esc\u00e1ndalo de la desigualdad 2 - Global Tax Justice","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/globaltaxjustice.org\/es\/noticias\/el-escandalo-de-la-desigualdad-2\/","og_locale":"es_ES","og_type":"article","og_title":"El esc\u00e1ndalo de la desigualdad 2 - Global Tax Justice","og_description":"Christian Aid acaba de publicar la versi\u00f3n actualizada de su estudio de 2012, \u201cEl esc\u00e1ndalo de la desigualdad 2\u201d, en el","og_url":"https:\/\/globaltaxjustice.org\/es\/noticias\/el-escandalo-de-la-desigualdad-2\/","og_site_name":"Global Tax Justice","og_image":[{"width":1024,"height":742,"url":"https:\/\/globaltaxjustice.org\/wp-content\/uploads\/2022\/08\/2017-03-31-El-escandalo-de-la-desigualdad-2-ES-IMAGEM-2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/globaltaxjustice.org\/es\/noticias\/el-escandalo-de-la-desigualdad-2\/","url":"https:\/\/globaltaxjustice.org\/es\/noticias\/el-escandalo-de-la-desigualdad-2\/","name":"El esc\u00e1ndalo de la desigualdad 2 - Global Tax Justice","isPartOf":{"@id":"https:\/\/globaltaxjustice.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/globaltaxjustice.org\/es\/noticias\/el-escandalo-de-la-desigualdad-2\/#primaryimage"},"image":{"@id":"https:\/\/globaltaxjustice.org\/es\/noticias\/el-escandalo-de-la-desigualdad-2\/#primaryimage"},"thumbnailUrl":"https:\/\/globaltaxjustice.org\/wp-content\/uploads\/2022\/08\/2017-03-31-El-escandalo-de-la-desigualdad-2-ES-IMAGEM-2.jpg","datePublished":"2022-08-11T20:35:06+00:00","breadcrumb":{"@id":"https:\/\/globaltaxjustice.org\/es\/noticias\/el-escandalo-de-la-desigualdad-2\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/globaltaxjustice.org\/es\/noticias\/el-escandalo-de-la-desigualdad-2\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/globaltaxjustice.org\/es\/noticias\/el-escandalo-de-la-desigualdad-2\/#primaryimage","url":"https:\/\/globaltaxjustice.org\/wp-content\/uploads\/2022\/08\/2017-03-31-El-escandalo-de-la-desigualdad-2-ES-IMAGEM-2.jpg","contentUrl":"https:\/\/globaltaxjustice.org\/wp-content\/uploads\/2022\/08\/2017-03-31-El-escandalo-de-la-desigualdad-2-ES-IMAGEM-2.jpg","width":1024,"height":742},{"@type":"BreadcrumbList","@id":"https:\/\/globaltaxjustice.org\/es\/noticias\/el-escandalo-de-la-desigualdad-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/globaltaxjustice.org\/es\/"},{"@type":"ListItem","position":2,"name":"News","item":"https:\/\/globaltaxjustice.org\/es\/noticias\/"},{"@type":"ListItem","position":3,"name":"El esc\u00e1ndalo de la desigualdad 2"}]},{"@type":"WebSite","@id":"https:\/\/globaltaxjustice.org\/es\/#website","url":"https:\/\/globaltaxjustice.org\/es\/","name":"Global Tax Justice","description":"Just another WordPress site","publisher":{"@id":"https:\/\/globaltaxjustice.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/globaltaxjustice.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/globaltaxjustice.org\/es\/#organization","name":"Global Tax Justice","url":"https:\/\/globaltaxjustice.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/globaltaxjustice.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/globaltaxjustice.org\/wp-content\/uploads\/2024\/10\/logo_header.svg","contentUrl":"https:\/\/globaltaxjustice.org\/wp-content\/uploads\/2024\/10\/logo_header.svg","width":229,"height":40,"caption":"Global Tax Justice"},"image":{"@id":"https:\/\/globaltaxjustice.org\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/globaltaxjustice.org\/es\/wp-json\/wp\/v2\/news\/6787","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/globaltaxjustice.org\/es\/wp-json\/wp\/v2\/news"}],"about":[{"href":"https:\/\/globaltaxjustice.org\/es\/wp-json\/wp\/v2\/types\/news"}],"version-history":[{"count":0,"href":"https:\/\/globaltaxjustice.org\/es\/wp-json\/wp\/v2\/news\/6787\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/globaltaxjustice.org\/es\/wp-json\/wp\/v2\/media\/6788"}],"wp:attachment":[{"href":"https:\/\/globaltaxjustice.org\/es\/wp-json\/wp\/v2\/media?parent=6787"}],"wp:term":[{"taxonomy":"thematic-area","embeddable":true,"href":"https:\/\/globaltaxjustice.org\/es\/wp-json\/wp\/v2\/thematic-area?post=6787"},{"taxonomy":"year","embeddable":true,"href":"https:\/\/globaltaxjustice.org\/es\/wp-json\/wp\/v2\/year?post=6787"},{"taxonomy":"resource-type","embeddable":true,"href":"https:\/\/globaltaxjustice.org\/es\/wp-json\/wp\/v2\/resource-type?post=6787"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}